{"id":69,"date":"2021-10-12T15:20:22","date_gmt":"2021-10-12T15:20:22","guid":{"rendered":"https:\/\/apply.heartviewcare.co.uk\/?page_id=69"},"modified":"2021-10-13T13:50:39","modified_gmt":"2021-10-13T13:50:39","slug":"login","status":"publish","type":"page","link":"https:\/\/apply.heartviewcare.co.uk\/index.php\/login\/","title":{"rendered":"Login"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"69\" class=\"elementor elementor-69\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4c68608 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4c68608\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9ba2f5b\" data-id=\"9ba2f5b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-128e0b8 elementor-widget elementor-widget-text-editor\" data-id=\"128e0b8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<center><strong><h3>Login To Application Portal<\/h3><\/strong><\/center>\r\n<div class=\"um um-login um-11\">\r\n\r\n\t<div class=\"um-form\">\r\n\r\n\t\t<form method=\"post\" action=\"\" autocomplete=\"off\">\r\n\r\n\t\t\t<div class=\"um-row _um_row_1 \" style=\"margin: 0 0 30px 0;\"><div class=\"um-col-1\"><div  id=\"um_field_11_username\" class=\"um-field um-field-text  um-field-username um-field-text um-field-type_text\" data-key=\"username\"><div class=\"um-field-label\"><label for=\"username-11\">Username or E-mail<\/label><div class=\"um-clear\"><\/div><\/div><div class=\"um-field-area\"><input  autocomplete=\"off\" class=\"um-form-field valid \" type=\"text\" name=\"username-11\" id=\"username-11\" value=\"\" placeholder=\"\" data-validate=\"unique_username_or_email\" data-key=\"username\" \/>\r\n\r\n\t\t\t\t\t\t<\/div><\/div><div  id=\"um_field_11_user_password\" class=\"um-field um-field-password  um-field-user_password um-field-password um-field-type_password\" data-key=\"user_password\"><div class=\"um-field-label\"><label for=\"user_password-11\">Password<\/label><div class=\"um-clear\"><\/div><\/div><div class=\"um-field-area\"><input class=\"um-form-field valid \" type=\"password\" name=\"user_password-11\" id=\"user_password-11\" value=\"\" placeholder=\"\" data-validate=\"\" data-key=\"user_password\" \/>\r\n\r\n\t\t\t\t\t\t<\/div><\/div><\/div><\/div>\t\t<input type=\"hidden\" name=\"form_id\" id=\"form_id_11\" value=\"11\" \/>\r\n\t\r\n\t<p class=\"um_request_name\">\r\n\t\t<label for=\"um_request_11\">Only fill in if you are not human<\/label>\r\n\t\t<input type=\"hidden\" name=\"um_request\" id=\"um_request_11\" class=\"input\" value=\"\" size=\"25\" autocomplete=\"off\" \/>\r\n\t<\/p>\r\n\r\n\t<input type=\"hidden\" id=\"_wpnonce\" name=\"_wpnonce\" value=\"bb05c26332\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/index.php\/wp-json\/wp\/v2\/pages\/69\" \/>\r\n\t<div class=\"um-col-alt\">\r\n\r\n\t\t\r\n\r\n\t\t\t<div class=\"um-field um-field-c\">\r\n\t\t\t\t<div class=\"um-field-area\">\r\n\t\t\t\t\t<label class=\"um-field-checkbox\">\r\n\t\t\t\t\t\t<input type=\"checkbox\" name=\"rememberme\" value=\"1\"  \/>\r\n\t\t\t\t\t\t<span class=\"um-field-checkbox-state\"><i class=\"um-icon-android-checkbox-outline-blank\"><\/i><\/span>\r\n\t\t\t\t\t\t<span class=\"um-field-checkbox-option\"> Keep me signed in<\/span>\r\n\t\t\t\t\t<\/label>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div class=\"um-clear\"><\/div>\r\n\t\t\r\n\t\t\t<div class=\"um-left um-half\">\r\n\t\t\t\t<input type=\"submit\" value=\"Login\" class=\"um-button\" id=\"um-submit-btn\" \/>\r\n\t\t\t<\/div>\r\n\t\t\t<div class=\"um-right um-half\">\r\n\t\t\t\t<a href=\"https:\/\/apply.heartviewcare.co.uk\/index.php\/register\/\" class=\"um-button um-alt\">\r\n\t\t\t\t\tRegister\t\t\t\t<\/a>\r\n\t\t\t<\/div>\r\n\r\n\t\t\r\n\t\t<div class=\"um-clear\"><\/div>\r\n\r\n\t<\/div>\r\n\r\n\t\r\n\t<div class=\"um-col-alt-b\">\r\n\t\t<a href=\"https:\/\/apply.heartviewcare.co.uk\/index.php\/password-reset\/\" class=\"um-link-alt\">\r\n\t\t\tForgot your password?\t\t<\/a>\r\n\t<\/div>\r\n\r\n\t\r\n\t\t<\/form>\r\n\r\n\t<\/div>\r\n\r\n<\/div><style type=\"text\/css\">\n.um-11.um {\n\tmax-width: 450px;\n}<\/style>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Login To Application Portal<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-69","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/apply.heartviewcare.co.uk\/index.php\/wp-json\/wp\/v2\/pages\/69","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apply.heartviewcare.co.uk\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/apply.heartviewcare.co.uk\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/apply.heartviewcare.co.uk\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apply.heartviewcare.co.uk\/index.php\/wp-json\/wp\/v2\/comments?post=69"}],"version-history":[{"count":16,"href":"https:\/\/apply.heartviewcare.co.uk\/index.php\/wp-json\/wp\/v2\/pages\/69\/revisions"}],"predecessor-version":[{"id":138,"href":"https:\/\/apply.heartviewcare.co.uk\/index.php\/wp-json\/wp\/v2\/pages\/69\/revisions\/138"}],"wp:attachment":[{"href":"https:\/\/apply.heartviewcare.co.uk\/index.php\/wp-json\/wp\/v2\/media?parent=69"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}